{"id":1343,"date":"2018-08-16T17:22:33","date_gmt":"2018-08-16T17:22:33","guid":{"rendered":"http:\/\/elperiodicodesaltillo.com\/wp\/?p=1343"},"modified":"2018-08-27T17:26:16","modified_gmt":"2018-08-27T17:26:16","slug":"alumnos-de-arquitectura-torreon-obtienen-primer-lugar-en-el-11-premio-nacional-del-acero","status":"publish","type":"post","link":"https:\/\/elperiodicodesaltillo.com\/wp\/2018\/08\/16\/alumnos-de-arquitectura-torreon-obtienen-primer-lugar-en-el-11-premio-nacional-del-acero\/","title":{"rendered":"Alumnos de Arquitectura Torre\u00f3n Obtienen Primer Lugar en el 11\u00b0 Premio Nacional del Acero"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1350\" src=\"http:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-8.jpg\" alt=\"\" width=\"960\" height=\"540\" srcset=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-8.jpg 960w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-8-300x169.jpg 300w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-8-768x432.jpg 768w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-8-696x392.jpg 696w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-8-747x420.jpg 747w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/p>\n<p><em><strong>SALTILLO, Coahuila. 16 de agosto de 2018.-<\/strong><\/em> Gracias a su trabajo, esfuerzo y dedicaci\u00f3n, estudiantes de la Facultad de Arquitectura Unidad Torre\u00f3n de la Universidad Aut\u00f3noma de Coahuila, obtuvieron el primer lugar en el 11\u00b0 Premio Nacional del Acero para Estudiantes de Arquitectura 2018, mismo que les brind\u00f3 el pase para representar al pa\u00eds y a la m\u00e1xima casa de estudios en evento internacional en Cartagena, Colombia en el mes de noviembre.<\/p>\n<p>A trav\u00e9s de la C\u00e1mara Nacional de la Industria Del Hierro y Del Acero, se convoc\u00f3 a estudiantes de los dos \u00faltimos a\u00f1os de la carrera de Arquitectura de todo el pa\u00eds a participar en la onceava edici\u00f3n del Premio Nacional del Acero y crear una propuesta arquitect\u00f3nica integral de un Pabell\u00f3n Invernadero para un Parque Bot\u00e1nico.<\/p>\n<p>Atendieron la convocatoria, los alumnos Daniel Mac\u00edas Vega, Mario C\u00e9sar Mart\u00ednez Reyes, Israel Alejandro Ram\u00edrez L\u00f3pez, Javier Alejandro Castro de \u00c1vila y los asesores Jorge Villanueva Sol\u00eds, C\u00e9sar Ponce Palafox y Gonzalo Jos\u00e9 Francisco P\u00e9rez G\u00f3mez Mart\u00ednez, e inscribieron un proyecto con el que obtuvieron el primer lugar del certamen.<\/p>\n<p>El concurso buscaba que los estudiantes presentaran propuestas arquitect\u00f3nicas integrales de un Pabell\u00f3n Invernadero para un Parque Bot\u00e1nico que contemplara aspectos urbanos, de accesibilidad y sustentabilidad, tecnol\u00f3gicos, estructurales, de representaci\u00f3n, entre otros y que \u00fanicamente se pueda realizar en acero.<\/p>\n<p>Los participantes desarrollaron proyectos en los que el acero no fuera visto \u00fanicamente como protagonista estructural, sino como una herramienta potencial de dise\u00f1o arquitect\u00f3nico, desafiando el uso tradicional de los materiales en la construcci\u00f3n.<\/p>\n<p>Uno de los galardonados, Daniel Mac\u00edas Vega, destac\u00f3 que la elaboraci\u00f3n del proyecto de Jard\u00edn Bot\u00e1nico tuvo un proceso aproximado de cinco meses, y gracias al trabajo de sus compa\u00f1eros, as\u00ed como al apoyo de los asesores y directivos de la Facultad, obtuvieron el pase a la final del concurso nacional.<\/p>\n<p>Agreg\u00f3 que, como parte del premio por obtener el primer lugar, se hicieron acreedores a un pase al 11\u00b0 Concurso ALACERO 2018, que se llevar\u00e1 a cabo en Cartagena de Indias, Colombia, en noviembre pr\u00f3ximo, teniendo la oportunidad de representar a M\u00e9xico y a la UA de C a nivel internacional.<\/p>\n<p>Como parte de la experiencia de representar a la m\u00e1xima casa de estudios de Coahuila a nivel nacional, Mac\u00edas Vega indic\u00f3 que la calidad de la educaci\u00f3n que recibe en la Facultad le permite desarrollar conocimientos y habilidades para competir acad\u00e9micamente con instituciones de todo el pa\u00eds.<\/p>\n<p>Finalmente, agradeci\u00f3 a las autoridades universitarias y directivas por el apoyo brindado a \u00e9l y sus compa\u00f1eros para representar a la UA de C a nivel nacional e internacional, asimismo, exhort\u00f3 a los universitarios a continuar participando en convocatorias que les permitan poner a prueba y ampliar sus habilidades y conocimientos.<\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #td_uid_1_6a0415e3c4357  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-7-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a0415e3c4357  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-5-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a0415e3c4357  .td-doubleSlider-2 .td-item3 {\r\n                        background: url(https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-4-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a0415e3c4357  .td-doubleSlider-2 .td-item4 {\r\n                        background: url(https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-3-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a0415e3c4357  .td-doubleSlider-2 .td-item5 {\r\n                        background: url(https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-2-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a0415e3c4357  .td-doubleSlider-2 .td-item6 {\r\n                        background: url(https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-6-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"td_uid_1_6a0415e3c4357\" class=\"td-gallery td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> of 6<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-7.jpg\" title=\"phoca_thumb_m_primer lugar arquitectura 7\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-7-747x420.jpg\" srcset=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-7-747x420.jpg 747w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-7-300x169.jpg 300w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-7-768x432.jpg 768w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-7-696x392.jpg 696w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-7.jpg 960w\" sizes=\"(max-width: 747px) 100vw, 747px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-5.jpg\" title=\"phoca_thumb_m_primer lugar arquitectura 5\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-5-747x420.jpg\" srcset=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-5-747x420.jpg 747w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-5-300x169.jpg 300w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-5-768x432.jpg 768w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-5-696x392.jpg 696w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-5.jpg 960w\" sizes=\"(max-width: 747px) 100vw, 747px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item3\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-4.jpg\" title=\"phoca_thumb_m_primer lugar arquitectura 4\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-4-747x420.jpg\" srcset=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-4-747x420.jpg 747w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-4-300x169.jpg 300w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-4-768x432.jpg 768w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-4-696x392.jpg 696w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-4.jpg 960w\" sizes=\"(max-width: 747px) 100vw, 747px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item4\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-3.jpg\" title=\"phoca_thumb_m_primer lugar arquitectura 3\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-3-747x420.jpg\" srcset=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-3-747x420.jpg 747w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-3-300x169.jpg 300w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-3-768x432.jpg 768w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-3-696x392.jpg 696w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-3.jpg 960w\" sizes=\"(max-width: 747px) 100vw, 747px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item5\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-2.jpg\" title=\"phoca_thumb_m_primer lugar arquitectura 2\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-2-747x420.jpg\" srcset=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-2-747x420.jpg 747w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-2-300x169.jpg 300w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-2-768x432.jpg 768w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-2-696x392.jpg 696w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-2.jpg 960w\" sizes=\"(max-width: 747px) 100vw, 747px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item6\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-6.jpg\" title=\"phoca_thumb_m_primer lugar arquitectura 6\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-6-747x420.jpg\" srcset=\"https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-6-747x420.jpg 747w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-6-300x169.jpg 300w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-6-768x432.jpg 768w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-6-696x392.jpg 696w, https:\/\/elperiodicodesaltillo.com\/wp\/wp-content\/uploads\/2018\/08\/phoca_thumb_m_primer-lugar-arquitectura-6.jpg 960w\" sizes=\"(max-width: 747px) 100vw, 747px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item3\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item4\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item5\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item6\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 16 de agosto de 2018.- Gracias a su trabajo, esfuerzo y dedicaci\u00f3n, estudiantes de la Facultad de Arquitectura Unidad Torre\u00f3n de la Universidad Aut\u00f3noma de Coahuila, obtuvieron el primer lugar en el 11\u00b0 Premio Nacional del Acero para Estudiantes de Arquitectura 2018, mismo que les brind\u00f3 el pase para representar al pa\u00eds y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1350,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[29,44,39,112,123,37],"class_list":["post-1343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universidad","tag-coahuila","tag-educacion","tag-saltillo","tag-salvador-hernandez-velez","tag-uadec","tag-universidad"],"_links":{"self":[{"href":"https:\/\/elperiodicodesaltillo.com\/wp\/wp-json\/wp\/v2\/posts\/1343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elperiodicodesaltillo.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elperiodicodesaltillo.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elperiodicodesaltillo.com\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elperiodicodesaltillo.com\/wp\/wp-json\/wp\/v2\/comments?post=1343"}],"version-history":[{"count":1,"href":"https:\/\/elperiodicodesaltillo.com\/wp\/wp-json\/wp\/v2\/posts\/1343\/revisions"}],"predecessor-version":[{"id":1351,"href":"https:\/\/elperiodicodesaltillo.com\/wp\/wp-json\/wp\/v2\/posts\/1343\/revisions\/1351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elperiodicodesaltillo.com\/wp\/wp-json\/wp\/v2\/media\/1350"}],"wp:attachment":[{"href":"https:\/\/elperiodicodesaltillo.com\/wp\/wp-json\/wp\/v2\/media?parent=1343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elperiodicodesaltillo.com\/wp\/wp-json\/wp\/v2\/categories?post=1343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elperiodicodesaltillo.com\/wp\/wp-json\/wp\/v2\/tags?post=1343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}